{"id":24230,"date":"2022-09-12T11:26:00","date_gmt":"2022-09-12T09:26:00","guid":{"rendered":"https:\/\/www.monkitsolaire.fr\/blog\/penurie-electricite-france\/"},"modified":"2023-12-12T16:45:32","modified_gmt":"2023-12-12T15:45:32","slug":"penurie-electricite-france","status":"publish","type":"post","link":"https:\/\/www.monkitsolaire.fr\/blog\/penurie-electricite-france-n378","title":{"rendered":"La France va-t-elle vivre une p\u00e9nurie en \u00e9lectricit\u00e9 ?"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p>Tandis que la production d\u2019\u00e9lectricit\u00e9 en France se contracte, <strong>la Premi\u00e8re Ministre Elisabeth Borne<\/strong> a annonc\u00e9 que notre pays pourrait \u00eatre en situation de <strong>p\u00e9nurie en \u00e9lectricit\u00e9 cet automne et cet hiver.<\/strong> Pourquoi en est-on arriv\u00e9 l\u00e0 ? Et quels sont les moyens pour \u00e9viter la p\u00e9nurie ? Mon Kit Solaire vous donne quelques cl\u00e9s pour mieux comprendre la situation.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pourquoi_parle-t-on_de_penurie_delectricite\"><\/span>Pourquoi parle-t-on de p\u00e9nurie d\u2019\u00e9lectricit\u00e9 ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Une conjonction d\u2019\u00e9l\u00e9ments explique aujourd\u2019hui pourquoi<strong> l\u2019Europe est menac\u00e9e de manquer d\u2019\u00e9lectricit\u00e9<\/strong>. De nombreux observateurs et experts alertent en effet sur le risque que la production europ\u00e9enne d\u2019\u00e9lectricit\u00e9 ne soit pas suffisante pour couvrir les besoins de la population, d\u00e8s cet automne.&nbsp;<\/p>\n\n\n\n<p>Ces raisons sont au nombre de trois.&nbsp;<\/p>\n\n\n\n<p>D\u2019abord, <strong>la situation g\u00e9opolitique en Ukraine<\/strong> <strong>a tendu la fourniture de gaz<\/strong> : en r\u00e9ponse aux <strong>sanctions \u00e9conomiques<\/strong> d\u00e9cid\u00e9es par l\u2019Union Europ\u00e9enne, la Russie a en effet r\u00e9duit\/suspendu ses exportations de gaz en direction des pays europ\u00e9ens. En cons\u00e9quence, <strong>le prix du gaz a explos\u00e9<\/strong>. Or, une partie du courant de grands pays, tels que l\u2019Allemagne, est produite \u00e0 partir du gaz. Pour compenser ce d\u00e9ficit, ces pays vont se tourner vers leurs voisins. L\u2019Union Europ\u00e9enne pr\u00e9voit en effet un dispositif de <strong>redistribution de l\u2019\u00e9lectricit\u00e9 entre ses pays membres<\/strong>. Mais la France ne pourra peut-\u00eatre pas produire suffisamment d\u2019\u00e9lectricit\u00e9 pour couvrir ses besoins domestiques et r\u00e9pondre par ailleurs \u00e0 la demande des pays voisins.<\/p>\n\n\n\n<p>Ce qui nous am\u00e8ne \u00e0 la deuxi\u00e8me raison pouvant expliquer cette situation de p\u00e9nurie. <strong>L\u2019\u00e9lectricit\u00e9 fran\u00e7aise est principalement issue de son parc nucl\u00e9aire<\/strong>. Toutefois, ce dernier est vieillissant et de nombreuses centrales nucl\u00e9aires (pr\u00e8s de la moiti\u00e9) sont aujourd\u2019hui \u00e0 l\u2019arr\u00eat, pour cause de r\u00e9vision ou de r\u00e9paration. Ce qui gr\u00e8ve, de fait, la production d\u2019\u00e9lectricit\u00e9 sur le territoire m\u00e9tropolitain. D\u2019autant que <strong>la France est en retard sur la production \u00e9lectrique renouvelable<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"710\" src=\"https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/penurie-electricite-france.jpg\" alt=\"P\u00e9nurie \u00e9lectricit\u00e9 France\" class=\"wp-image-28674\" srcset=\"https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/penurie-electricite-france.jpg 1000w, https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/penurie-electricite-france-300x213.jpg 300w, https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/penurie-electricite-france-768x545.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>Enfin, <strong>la s\u00e9cheresse connue en Europe<\/strong> cet \u00e9t\u00e9 a aussi eu un effet n\u00e9faste sur la production d\u2019hydro\u00e9lectricit\u00e9 en Norv\u00e8ge. <strong>Le premier exportateur d\u2019\u00e9lectricit\u00e9 en Europe<\/strong> poss\u00e8de en effet 1700 centrales hydro-\u00e9lectriques. Mais <strong>les barrages qui les alimentent se sont peu \u00e0 peu ass\u00e9ch\u00e9s<\/strong> du fait des temp\u00e9ratures exceptionnellement \u00e9lev\u00e9es de cet \u00e9t\u00e9. Un d\u00e9ficit de production est donc \u00e9galement \u00e0 pr\u00e9voir en Norv\u00e8ge, ce qui a une incidence sur l\u2019approvisionnement en \u00e9nergie de toute l\u2019Europe.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"La_France_sera-t-elle_touchee_par_une_penurie_en_electricite\"><\/span>La France sera-t-elle touch\u00e9e par une p\u00e9nurie en \u00e9lectricit\u00e9 ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Alors qu\u2019elle \u00e9tait jusque-l\u00e0 <strong>un des plus gros pays exportateurs d\u2019\u00e9lectricit\u00e9 en Europe<\/strong>, la France a import\u00e9 de l\u2019\u00e9lectricit\u00e9 cette ann\u00e9e.&nbsp;<\/p>\n\n\n\n<p>Pour expliquer cet inversement de tendance, il faut remonter \u00e0 2021. En d\u00e9cembre, un contr\u00f4le de routine \u00e0 r\u00e9v\u00e9l\u00e9 un probl\u00e8me de corrosion dans une <strong>centrale nucl\u00e9aire de la Vienne<\/strong>. Le m\u00eame probl\u00e8me a \u00e9t\u00e9 rep\u00e9r\u00e9 dans plusieurs centrales, entra\u00eenant l\u2019arr\u00eat de 12 r\u00e9acteurs. Il faut ajouter \u00e0 cela le nombre record de r\u00e9acteurs en maintenance, portant \u00e0 27 sur 56 le nombre de r\u00e9acteurs hors fonction.&nbsp;<\/p>\n\n\n\n<p>De plus, avec <strong>la s\u00e9cheresse de cet \u00e9t\u00e9<\/strong>, les cours d\u2019eau utilis\u00e9s pour refroidir les r\u00e9acteurs sont mont\u00e9s en temp\u00e9rature. Certaines unit\u00e9s ont \u00e9t\u00e9 dans l\u2019obligation de restreindre leur production.<\/p>\n\n\n\n<p>En cons\u00e9quence, <strong>la capacit\u00e9 de production journali\u00e8re d\u2019\u00e9lectricit\u00e9 des centrales nucl\u00e9aires est d\u2019environ 27 gigawatts (GW)<\/strong>, ce qui porterait la production \u00e0 280 \u00e0 300 TWH sur l\u2019ensemble de l\u2019ann\u00e9e 2022.&nbsp;<\/p>\n\n\n\n<p>Il faut savoir qu\u2019au cours des ann\u00e9es pr\u00e9c\u00e9dentes, <strong>la France produisait environ 400 TWH d&rsquo;\u00e9lectricit\u00e9 nucl\u00e9aire<\/strong>. Elle d\u00e9gageait une capacit\u00e9 d\u2019exportation l\u2019\u00e9t\u00e9 mais elle avait tout de m\u00eame besoin d\u2019importer de l\u2019\u00e9nergie l\u2019hiver. Avec la baisse de la production, la France devra donc importer encore plus d\u2019\u00e9lectricit\u00e9 alors que ces partenaires habituels (Belgique, Allemagne) seront eux aussi dans une situation tendue.<\/p>\n\n\n\n<p>Ainsi, <strong>si le froid s\u2019installe durablement en Europe cet hiver<\/strong>, q<strong>ue le vent souffle peu en mer du Nord<\/strong> et qu\u2019<strong>EDF ne remonte pas sa production d\u2019\u00e9lectricit\u00e9 nucl\u00e9aire<\/strong>, une p\u00e9nurie pourrait se faire sentir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Peut-il_y_avoir_un_risque_de_black-out_cet_hiver_en_France\"><\/span>Peut-il y avoir un risque de black-out cet hiver en France ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>Un black-out<\/strong> est une panne de courant g\u00e9n\u00e9ralis\u00e9e. <strong>La derni\u00e8re remonte au 19 d\u00e9cembre 1978<\/strong>. Pour \u00e9viter que cet incident grave du r\u00e9seau \u00e9lectrique ne se reproduise, <strong>le RTE (le r\u00e9seau de distribution \u00e9lectrique)<\/strong> a mis sur pied divers plans de <strong>d\u00e9lestage<\/strong>, c\u2019est-\u00e0-dire de coupures de courant pr\u00e9ventives, cibl\u00e9es et tr\u00e8s temporaires.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"670\" src=\"https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/risque-penurie-electricite.jpg\" alt=\"Risque p\u00e9nurie \u00e9lectricit\u00e9\" class=\"wp-image-28675\" srcset=\"https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/risque-penurie-electricite.jpg 1000w, https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/risque-penurie-electricite-300x201.jpg 300w, https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/risque-penurie-electricite-768x515.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quels_moyens_pour_eviter_une_situation_de_black-out_electrique\"><\/span>Quels moyens pour \u00e9viter une situation de black-out \u00e9lectrique ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Plusieurs moyens peuvent permettrent de soulager le r\u00e9seau en cas de <strong>demande sup\u00e9rieure \u00e0 la capacit\u00e9 de fourniture d&rsquo;\u00e9lectricit\u00e9<\/strong>, dont la plus connue est le <strong>d\u00e9lestage<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Il s\u2019agit d\u2019<strong>anticiper des coupures d\u2019\u00e9lectricit\u00e9<\/strong> temporaires sur des zones localis\u00e9es et tournantes. En clair, <strong>RTE pourrait couper l\u2019\u00e9lectricit\u00e9 de 200.000 foyers durant deux heures maximum<\/strong> \u00e0 tour de r\u00f4le, ainsi que stopper l\u2019approvisionnement de certaines entreprises. Les entreprises <strong>les plus gourmandes en \u00e9nergie seraient les plus cibl\u00e9es<\/strong> dans un premier temps.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quels_sont_les_evolutions_du_prix_delectricite_que_la_France_a_connu\"><\/span>Quels sont les \u00e9volutions du prix d\u2019\u00e9lectricit\u00e9 que la France a connu ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Les prix de gros de l\u2019\u00e9lectricit\u00e9 en France ont connu de tr\u00e8s importantes variations en l\u2019espace d\u2019un an :<strong> plus de 1 000\u20ac par mWh en ao\u00fbt 2022 contre 70\u20ac l\u2019an dernier<\/strong> !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quelles_habitudes_mettre_en_place_pour_reduire_sa_consommation_en_electricite\"><\/span>Quelles habitudes mettre en place pour r\u00e9duire sa consommation en \u00e9lectricit\u00e9 ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Pour \u00e9viter le <strong>back-out<\/strong> et\/ou le recours au <strong>d\u00e9lestage<\/strong>, les Fran\u00e7ais, qu\u2019ils soient particuliers ou professionnels, ont un r\u00f4le \u00e0 jouer.<\/p>\n\n\n\n<p>Certains comportements du quotidien pourraient permettre de <strong>r\u00e9duire la consommation globale du pays<\/strong> et ainsi soulager le r\u00e9seau, tels que pr\u00e9conis\u00e9 par l\u2019ADEME :&nbsp;<\/p>\n\n\n\n<ul>\n<li>Avoir recours <strong>plus massivement au t\u00e9l\u00e9travail<\/strong> ;<\/li>\n\n\n\n<li><strong>Baisser la temp\u00e9rature du chauffage d\u20191\u00b0C<\/strong> (autour de 20\u2103 dans les pi\u00e8ces \u00e0 vivre, 17\u2103 dans les chambres) et mettre ses radiateurs en mode hors gel lors d\u2019une absence prolong\u00e9e ;<\/li>\n\n\n\n<li>Installer une r\u00e9gulation et une programmation du chauffage ;<\/li>\n\n\n\n<li><strong>\u00c9teindre les appareils<\/strong> plut\u00f4t que les laisser en veille ;<\/li>\n\n\n\n<li>Privil\u00e9gier les lampes LED pour l\u2019\u00e9clairage de votre maison ;<\/li>\n\n\n\n<li>\u00c9teindre les lumi\u00e8res inutiles ;<\/li>\n\n\n\n<li>Choisir de pr\u00e9f\u00e9rence les programmes \u201c\u00e9co\u201d de votre machine \u00e0 laver et de votre lave-vaisselle ; ne les utiliser que lorsqu\u2019ils sont pleins ;<\/li>\n\n\n\n<li>Privil\u00e9gier le s\u00e9chage du linge \u00e0 l\u2019air plut\u00f4t qu\u2019utiliser un s\u00e8che-linge ;<\/li>\n\n\n\n<li>Cuisiner en couvrant les casseroles ;<\/li>\n\n\n\n<li>Choisir des \u00e9crans TV de taille raisonnable ;<\/li>\n\n\n\n<li><strong>D\u00e9brancher les appareils \u00e9lectriques non utilis\u00e9s<\/strong> (TV, box, console de jeux, ordinateur) ;<\/li>\n\n\n\n<li>Scruter les \u00e9tiquettes \u00e9nerg\u00e9tiques ;&nbsp;<\/li>\n\n\n\n<li><strong>\u00c9conomiser l\u2019eau chaude<\/strong> ;<\/li>\n\n\n\n<li>Programmer la temp\u00e9rature de votre ballon d\u2019eau chaude entre 50 \u2103 et 55 \u2103, entourer le ballon d\u2019eau chaude et ses tuyaux avec un isolant ;<\/li>\n\n\n\n<li>Bloquer les courants d\u2019air froid : fermer les volets la nuit (et m\u00eame le jour en cas de grand froid si l\u2019habitant n\u2019est pas pr\u00e9sent), installer des rideaux \u00e9pais aux fen\u00eatres ou s\u00e9parant les pi\u00e8ces chauff\u00e9es des lieux non chauff\u00e9s ;<\/li>\n\n\n\n<li><strong>Renforcer l\u2019isolation de sa maison<\/strong> ;<\/li>\n\n\n\n<li>Reporter certaines actions dans le temps (la nuit plut\u00f4t que le jour) et profiter au passage des heures creuses pour mettre sa machine \u00e0 laver ou son lave-vaisselle en marche.<\/li>\n<\/ul>\n\n\n\n<p>En outre, vous pouvez <strong>opter pour l\u2019autoconsommation \u00e9lectrique<\/strong>. Les panneaux photovolta\u00efques en toiture en autoconsommation vous permettent de <strong>produire votre propre \u00e9lectricit\u00e9<\/strong>. Gr\u00e2ce \u00e0 cela, votre demande en \u00e9lectricit\u00e9 au niveau du r\u00e9seau EDF baisse et vous contribuez \u00e0 soulager le r\u00e9seau.&nbsp;<\/p>\n\n\n\n<p><span style=\"text-decoration: underline;\">Autre avantage<\/span> : si un d\u00e9lestage intervient, vous ne serez pas sans \u00e9lectricit\u00e9 ! Pensez donc \u00e0 vous munir de batteries !<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"667\" src=\"https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/penurie-electricite-comment-se-preparer.jpg\" alt=\"P\u00e9nurie \u00e9lectricit\u00e9 comment se pr\u00e9parer\" class=\"wp-image-28676\" srcset=\"https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/penurie-electricite-comment-se-preparer.jpg 1000w, https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/penurie-electricite-comment-se-preparer-300x200.jpg 300w, https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/06\/penurie-electricite-comment-se-preparer-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusion<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>M\u00eame s\u2019il n\u2019est pas certain, le <strong>risque de p\u00e9nurie d\u2019\u00e9lectricit\u00e9<\/strong>, et par cons\u00e9quent de d\u00e9lestage, est tout de m\u00eame probable, <strong>compte-tenu de la guerre en Ukraine<\/strong>, de la baisse de la production nucl\u00e9aire en France et hydro\u00e9lectrique en Norv\u00e8ge.<\/p>\n\n\n\n<p>Une prise de conscience collective peut aider \u00e0 soulager le r\u00e9seau, notamment vis-\u00e0-vis des <strong>\u00e9nergies renouvelables<\/strong>. Car d\u00e9velopper le recours des particuliers \u00e0 <strong>l\u2019\u00e9nergie solaire en toiture en autoconsommation<\/strong> pourrait permettre de r\u00e9duire la demande globale d\u2019\u00e9lectricit\u00e9 et r\u00e9duire les risques de p\u00e9nurie.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a437adb4 alignwide uagb-is-root-container\">\n<h2 class=\"wp-block-heading\" style=\"text-transform:uppercase\"><span class=\"ez-toc-section\" id=\"Questions_frequentes_sur_la_penurie_delectricite_en_France\"><\/span>Questions fr\u00e9quentes sur la p\u00e9nurie d&rsquo;\u00e9lectricit\u00e9 en France<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-uagb-faq uagb-faq__outer-wrap uagb-block-f250aac6 uagb-faq-icon-row-reverse uagb-faq-layout-accordion uagb-faq-expand-first-true uagb-faq-inactive-other-true uagb-faq__wrap uagb-buttons-layout-wrap uagb-faq-equal-height     question_faq\" data-faqtoggle=\"true\" role=\"tablist\"><script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"@id\":\"https:\\\/\\\/www.monkitsolaire.fr\\\/blog\\\/penurie-electricite-france-n378\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"RTE a-t-elle d\\u2019autres moyens que le d\\u00e9lestage pour \\u00e9viter le black-out ?\\u00a0\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Oui, il existe deux autres moyens pour r\\u00e9duire les tensions sur le r\\u00e9seau. D\\u2019abord, ce que l\\u2019on appelle le m\\u00e9canisme d\\u2019interruptibilit\\u00e9, qui pr\\u00e9voit, sur la base du volontariat et moyennant une compensation financi\\u00e8re, de couper le courant aux industries les plus consommatrices d\\u2019\\u00e9lectricit\\u00e9. Ensuite, la RTE peut bri\\u00e8vement baisser la tension sur le r\\u00e9seau \\u00e9lectrique pour r\\u00e9duire la pression sur le r\\u00e9seau.\"}},{\"@type\":\"Question\",\"name\":\"Qui est le plus concern\\u00e9 par le d\\u00e9lestage ?\\u00a0\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Les particuliers et les entreprises vivant en zones rurales sont plus susceptibles de conna\\u00eetre des \\u00e9pisodes de d\\u00e9lestage. En effet, certains sites, tels que les h\\u00f4pitaux, les centres de gestion des appels d\\u2019urgence ou encore des services auxiliaires des postes de haute tension qui acheminent l\\u2019\\u00e9lectricit\\u00e9 sont aliment\\u00e9s en priorit\\u00e9 et se situent g\\u00e9n\\u00e9ralement en ville.\"}},{\"@type\":\"Question\",\"name\":\"Peut-on pr\\u00e9voir un d\\u00e9lestage ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Oui, il s\\u2019agit d\\u2019un acte planifi\\u00e9. Le RTE pr\\u00e9vient donc, via les m\\u00e9dia, les d\\u00e9lestages \\u00e0 venir.\"}}]}<\/script><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-4b46bc4d \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M192 384c-8.188 0-16.38-3.125-22.62-9.375l-160-160c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L192 306.8l137.4-137.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-160 160C208.4 380.9 200.2 384 192 384z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M352 352c-8.188 0-16.38-3.125-22.62-9.375L192 205.3l-137.4 137.4c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25l160-160c12.5-12.5 32.75-12.5 45.25 0l160 160c12.5 12.5 12.5 32.75 0 45.25C368.4 348.9 360.2 352 352 352z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<h3 class=\"uagb-question\">RTE a-t-elle d\u2019autres moyens que le d\u00e9lestage pour \u00e9viter le black-out ?\u00a0<\/h3><\/div><div class=\"uagb-faq-content\"><p>Oui, il existe deux autres moyens pour r\u00e9duire les tensions sur le r\u00e9seau. D\u2019abord, ce que l\u2019on appelle le m\u00e9canisme d\u2019interruptibilit\u00e9, qui pr\u00e9voit, sur la base du volontariat et moyennant une compensation financi\u00e8re, de couper le courant aux industries les plus consommatrices d\u2019\u00e9lectricit\u00e9. Ensuite, la RTE peut bri\u00e8vement baisser la tension sur le r\u00e9seau \u00e9lectrique pour r\u00e9duire la pression sur le r\u00e9seau.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-fcb697d9 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M192 384c-8.188 0-16.38-3.125-22.62-9.375l-160-160c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L192 306.8l137.4-137.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-160 160C208.4 380.9 200.2 384 192 384z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M352 352c-8.188 0-16.38-3.125-22.62-9.375L192 205.3l-137.4 137.4c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25l160-160c12.5-12.5 32.75-12.5 45.25 0l160 160c12.5 12.5 12.5 32.75 0 45.25C368.4 348.9 360.2 352 352 352z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<h3 class=\"uagb-question\">Qui est le plus concern\u00e9 par le d\u00e9lestage ?\u00a0<\/h3><\/div><div class=\"uagb-faq-content\"><p>Les particuliers et les entreprises vivant en zones rurales sont plus susceptibles de conna\u00eetre des \u00e9pisodes de d\u00e9lestage. En effet, certains sites, tels que les h\u00f4pitaux, les centres de gestion des appels d\u2019urgence ou encore des services auxiliaires des postes de haute tension qui acheminent l\u2019\u00e9lectricit\u00e9 sont aliment\u00e9s en priorit\u00e9 et se situent g\u00e9n\u00e9ralement en ville.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-11dbaff7 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<h3 class=\"uagb-question\">Peut-on pr\u00e9voir un d\u00e9lestage ?<\/h3><\/div><div class=\"uagb-faq-content\"><p>Oui, il s\u2019agit d\u2019un acte planifi\u00e9. Le RTE pr\u00e9vient donc, via les m\u00e9dia, les d\u00e9lestages \u00e0 venir.<\/p><\/div><\/div><\/div><\/div>\n\n\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"22775\" class=\"elementor elementor-22775\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99a75c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99a75c1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f97b52\" data-id=\"6f97b52\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff89a97 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ff89a97\" data-element_type=\"widget\" id=\"titre_contact_blog\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><p class=\"elementor-heading-title elementor-size-default\">Besoin d\u2019aide pour finaliser votre projet solaire ?<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5518e4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b5518e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><span style=\"white-space: pre-wrap;\">Appelez maintenant ou choisissez un cr\u00e9neau horaire pour parler de votre projet avec nos experts.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0cbc040 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0cbc040\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-243b6f4\" data-id=\"243b6f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a27cbbd elementor-widget elementor-widget-button\" data-id=\"a27cbbd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"tel:0359897400\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">03 59 89 74 00<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-777f3ec\" data-id=\"777f3ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a17f7d7 btn-contact-calendly elementor-widget elementor-widget-button\" data-id=\"a17f7d7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.monkitsolaire.fr\/nous-contacter\/formulaire\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Prendre rendez-vous<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-98e2423 elementor-widget elementor-widget-text-editor\" data-id=\"98e2423\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><em><span style=\"white-space: pre-wrap;\">*Appel non surtax\u00e9 &#8211; Conseillers disponibles du lundi au vendredi de 8h \u00e0 19h<\/span><\/em><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"<p>Tandis que la production d\u2019\u00e9lectricit\u00e9 en France se contracte, la Premi\u00e8re Ministre Elisabeth Borne a annonc\u00e9 que notre pays pourrait \u00eatre en situation de p\u00e9nurie en \u00e9lectricit\u00e9 cet automne et cet hiver. Pourquoi en est-on arriv\u00e9 l\u00e0 ? Et quels sont les moyens pour \u00e9viter la p\u00e9nurie ? Mon Kit Solaire vous donne quelques cl\u00e9s [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":53218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_uag_custom_page_level_css":""},"categories":[1],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/12\/penurie-d-electricite.jpg",1200,630,false],"thumbnail":["https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/12\/penurie-d-electricite-150x150.jpg",150,150,true],"medium":["https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/12\/penurie-d-electricite-300x158.jpg",300,158,true],"medium_large":["https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/12\/penurie-d-electricite-768x403.jpg",768,403,true],"large":["https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/12\/penurie-d-electricite-1024x538.jpg",800,420,true],"1536x1536":["https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/12\/penurie-d-electricite.jpg",1200,630,false],"2048x2048":["https:\/\/www.monkitsolaire.fr\/blog\/wp-content\/uploads\/2023\/12\/penurie-d-electricite.jpg",1200,630,false]},"uagb_author_info":{"display_name":"L'\u00e9quipe MonKitSolaire","author_link":"https:\/\/www.monkitsolaire.fr\/blog"},"uagb_comment_info":0,"uagb_excerpt":"Tandis que la production d\u2019\u00e9lectricit\u00e9 en France se contracte, la Premi\u00e8re Ministre Elisabeth Borne a annonc\u00e9 que notre pays pourrait \u00eatre en situation de p\u00e9nurie en \u00e9lectricit\u00e9 cet automne et cet hiver. Pourquoi en est-on arriv\u00e9 l\u00e0 ? Et quels sont les moyens pour \u00e9viter la p\u00e9nurie ? Mon Kit Solaire vous donne quelques cl\u00e9s\u2026","_links":{"self":[{"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/posts\/24230"}],"collection":[{"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/comments?post=24230"}],"version-history":[{"count":6,"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/posts\/24230\/revisions"}],"predecessor-version":[{"id":53219,"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/posts\/24230\/revisions\/53219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/media\/53218"}],"wp:attachment":[{"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/media?parent=24230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/categories?post=24230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monkitsolaire.fr\/blog\/wp-json\/wp\/v2\/tags?post=24230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}